{"id":1793,"date":"2015-12-17T07:16:28","date_gmt":"2015-12-17T06:16:28","guid":{"rendered":"https:\/\/www.schoenruh-seefeld.com\/en\/wetter\/"},"modified":"2025-01-30T08:51:52","modified_gmt":"2025-01-30T07:51:52","slug":"weather","status":"publish","type":"page","link":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/","title":{"rendered":"Weather"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1793","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weather &#187; Wellnesshotel Sch\u00f6nruh<\/title>\n<meta name=\"description\" content=\"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weather &#187; Wellnesshotel Sch\u00f6nruh\" \/>\n<meta property=\"og:description\" content=\"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/\" \/>\n<meta property=\"og:site_name\" content=\"Wellnesshotel Sch\u00f6nruh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoenruh.seefeld\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T07:51:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schoenruh-seefeld.com\/wp-content\/uploads\/2018\/09\/Willkommen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1538\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/weather\\\/\",\"url\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/weather\\\/\",\"name\":\"Weather &#187; Wellnesshotel Sch\u00f6nruh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#website\"},\"datePublished\":\"2015-12-17T06:16:28+00:00\",\"dateModified\":\"2025-01-30T07:51:52+00:00\",\"description\":\"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/weather\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/weather\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/weather\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weather\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#website\",\"url\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/\",\"name\":\"Wellnesshotel Sch\u00f6nruh\",\"description\":\"Kaltschmid Hotels - Sch\u00f6nruh Seefeld\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#organization\",\"name\":\"Wellnesshotel Sch\u00f6nruh Seefeld\",\"url\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Logo-Sch\u00f6nruh.png\",\"contentUrl\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Logo-Sch\u00f6nruh.png\",\"width\":543,\"height\":124,\"caption\":\"Wellnesshotel Sch\u00f6nruh Seefeld\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schoenruh-seefeld.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoenruh.seefeld\\\/\",\"https:\\\/\\\/www.instagram.com\\\/hotel.schoenruh.seefeld\\\/\",\"https:\\\/\\\/www.youtube.com\\\/watch?v=GtpAuriho2I\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weather &#187; Wellnesshotel Sch\u00f6nruh","description":"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Weather &#187; Wellnesshotel Sch\u00f6nruh","og_description":"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;","og_url":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/","og_site_name":"Wellnesshotel Sch\u00f6nruh","article_publisher":"https:\/\/www.facebook.com\/schoenruh.seefeld\/","article_modified_time":"2025-01-30T07:51:52+00:00","og_image":[{"width":1538,"height":907,"url":"https:\/\/www.schoenruh-seefeld.com\/wp-content\/uploads\/2018\/09\/Willkommen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/","url":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/","name":"Weather &#187; Wellnesshotel Sch\u00f6nruh","isPartOf":{"@id":"https:\/\/www.schoenruh-seefeld.com\/#website"},"datePublished":"2015-12-17T06:16:28+00:00","dateModified":"2025-01-30T07:51:52+00:00","description":"4\u2605 Wellnesshotel Sch\u00f6nruh \u26f2 Weather Weather &#187;","breadcrumb":{"@id":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schoenruh-seefeld.com\/en\/weather\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schoenruh-seefeld.com\/en\/weather\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schoenruh-seefeld.com\/en\/"},{"@type":"ListItem","position":2,"name":"Weather"}]},{"@type":"WebSite","@id":"https:\/\/www.schoenruh-seefeld.com\/#website","url":"https:\/\/www.schoenruh-seefeld.com\/","name":"Wellnesshotel Sch\u00f6nruh","description":"Kaltschmid Hotels - Sch\u00f6nruh Seefeld","publisher":{"@id":"https:\/\/www.schoenruh-seefeld.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schoenruh-seefeld.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.schoenruh-seefeld.com\/#organization","name":"Wellnesshotel Sch\u00f6nruh Seefeld","url":"https:\/\/www.schoenruh-seefeld.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schoenruh-seefeld.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.schoenruh-seefeld.com\/wp-content\/uploads\/2017\/03\/Logo-Sch\u00f6nruh.png","contentUrl":"https:\/\/www.schoenruh-seefeld.com\/wp-content\/uploads\/2017\/03\/Logo-Sch\u00f6nruh.png","width":543,"height":124,"caption":"Wellnesshotel Sch\u00f6nruh Seefeld"},"image":{"@id":"https:\/\/www.schoenruh-seefeld.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoenruh.seefeld\/","https:\/\/www.instagram.com\/hotel.schoenruh.seefeld\/","https:\/\/www.youtube.com\/watch?v=GtpAuriho2I"]}]}},"_links":{"self":[{"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/pages\/1793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/comments?post=1793"}],"version-history":[{"count":5,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/pages\/1793\/revisions"}],"predecessor-version":[{"id":49517,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/pages\/1793\/revisions\/49517"}],"wp:attachment":[{"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/media?parent=1793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/categories?post=1793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoenruh-seefeld.com\/en\/wp-json\/wp\/v2\/tags?post=1793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}